{"id":14458,"date":"2024-11-04T14:15:39","date_gmt":"2024-11-04T17:15:39","guid":{"rendered":"https:\/\/sub.labovet.com.br\/?post_type=negocios&#038;p=14458"},"modified":"2024-11-29T11:23:49","modified_gmt":"2024-11-29T14:23:49","slug":"venda-de-medicamentos-em-pet-shops-entenda-como-funcionam-as-regras","status":"publish","type":"negocios","link":"https:\/\/labovet.com.br\/es\/negocio\/venda-de-medicamentos-em-pet-shops-entenda-como-funcionam-as-regras","title":{"rendered":"VENDA DE MEDICAMENTOS EM PET SHOPS: ENTENDA COMO FUNCIONAM AS REGRAS"},"content":{"rendered":"<p>O seu <strong>pet shop<\/strong> se preocupa com o <strong>bem estar<\/strong> animal e a <strong>sa\u00fade<\/strong> dos <strong>bichinhos?<\/strong> Pois saiba que, desde o ano passado, uma <strong>norma<\/strong> do <strong>Conselho Federal de Medicina Veterin\u00e1ria<\/strong> passou a\u00a0exigir\u00a0que uma s\u00e9rie de medidas seja realizada em prol desses cuidados, inclusive a paralisa\u00e7\u00e3o da venda de medicamentos em pet shops.<\/p>\n<p>Para alguns <strong>empres\u00e1rios,<\/strong> a norma causou descontentamento e questionamento, j\u00e1 para os <strong>veterin\u00e1rios,<\/strong> as novas regras parecem razo\u00e1veis, especialmente considerando a <strong>sa\u00fade<\/strong> e o <strong>bem-estar dos animais<\/strong>. De toda forma, \u00e9 importante ficar atento, pois as multas pelo descumprimento podem ser pesadas!<\/p>\n<h2>Conhe\u00e7a a nova norma<\/h2>\n<p>Desde janeiro de 2015 est\u00e1 em vigor uma <strong>Resolu\u00e7\u00e3o do Conselho Federal de Medicina Veterin\u00e1ria<\/strong> (Resolu\u00e7\u00e3o CFMV n.\u00ba 1069\/14) que estabelece novas regras para os pet shops, visando o bem-estar dos animais. Algumas medidas como a venda de medicamentos em pet shops\u00a0e realiza\u00e7\u00e3o de procedimentos, por exemplo, n\u00e3o podem mais ser realizadas por esses estabelecimentos, que devem, inclusive, oferecer condi\u00e7\u00f5es adequadas para o bem-estar animal.<\/p>\n<h2>Venda de medicamentos em pet shops est\u00e1 proibida<\/h2>\n<p>Segundo a <strong>nova norma<\/strong>, os <strong>pet shops<\/strong> s\u00f3 poder\u00e3o<strong> vender produtos<\/strong> para os animais de estima\u00e7\u00e3o como <strong>brinquedos, shampoos, roupinhas, acess\u00f3rios<\/strong> e <strong>ra\u00e7\u00f5es.<\/strong> A venda de <strong>medicamentos,<\/strong>\u00a0a aplica\u00e7\u00e3o de <strong>vacinas,<\/strong> bem como, a realiza\u00e7\u00e3o de pequenos procedimentos e cirurgias\u00a0devem ficar restritas aos <strong>consult\u00f3rios<\/strong> e <strong>cl\u00ednicas<\/strong> veterin\u00e1rias <strong>especializadas.<\/strong><\/p>\n<h2>Sa\u00fade para os bichinhos<\/h2>\n<p>Para o <strong>Conselho Federal de Medicina Veterin\u00e1ria<\/strong>, a realiza\u00e7\u00e3o de pequenos <strong>procedimentos, cirurgias<\/strong> ou mesmo a aplica\u00e7\u00e3o de <strong>vacinas<\/strong> \u00e9 <strong>contraindicada<\/strong> no caso de <strong>pet shops<\/strong> por uma quest\u00e3o de sa\u00fade e bem-estar dos animais. Esses procedimentos devem ser realizados por <strong>m\u00e9dicos veterin\u00e1rios capacitados<\/strong>, que possuem forma\u00e7\u00e3o espec\u00edfica para avaliar a dosagens de medicamentos e tamb\u00e9m t\u00e9cnicas cir\u00fargicas.<\/p>\n<h2>Bem-estar do pet<\/h2>\n<p>A <strong>nova norma<\/strong> tamb\u00e9m determina que os <strong>pet shops<\/strong> tenham alguns <strong>cuidados<\/strong> com o <strong>bem-estar animal<\/strong>. Al\u00e9m de oferecer <strong>boas condi\u00e7\u00f5es de higiene<\/strong>, os estabelecimentos devem contar com uma <strong>luminosidade<\/strong> adequada e <strong>pouco barulho<\/strong>, evitando, assim, o estresse dos bichinhos.<\/p>\n<h2>Supervis\u00e3o de veterin\u00e1rios<\/h2>\n<p>Uma das <strong>medidas<\/strong> que mais gerou controv\u00e9rsias com rela\u00e7\u00e3o \u00e0 <strong>nova Resolu\u00e7\u00e3o<\/strong>, al\u00e9m da proibi\u00e7\u00e3o da venda de medicamentos em pet shops,\u00a0diz respeito \u00e0 exig\u00eancia de um veterin\u00e1rio respons\u00e1vel pelo estabelecimento. Segundo a norma, esse profissional deve <strong>supervisionar<\/strong> as condi\u00e7\u00f5es \u00e0s quais os animais ficam expostos, bem como\u00a0<strong>assegurar<\/strong> que os servi\u00e7os prestados estejam de acordo com <strong>boas pr\u00e1ticas<\/strong> veterin\u00e1rias. Muitos propriet\u00e1rios n\u00e3o gostaram da <strong>nova exig\u00eancia<\/strong>, pois acreditam que as condi\u00e7\u00f5es de <strong>bem-estar<\/strong> s\u00e3o proporcionadas pelo tratamento dos bichinhos, e a presen\u00e7a de um <strong>veterin\u00e1rio<\/strong> acaba sendo indiferente, al\u00e9m de gerar custos decorrentes da contrata\u00e7\u00e3o desse profissional.<\/p>\n<p>Pela norma, os <strong>pet shops<\/strong> devem contratar um <strong>veterin\u00e1rio por tempo integral<\/strong> para desempenhar as fun\u00e7\u00f5es de <strong>supervis\u00e3o,<\/strong> com uma carga hor\u00e1ria m\u00ednima de seis horas semanais. Para o Conselho, essa medida n\u00e3o se trata de uma forma de reserva de mercado, mas, sim, de um procedimento que deve <strong>uniformizar<\/strong> os <strong>atendimentos<\/strong> e <strong>garantir a sa\u00fade<\/strong> e o <strong>bem-estar animal<\/strong>.<\/p>\n<h2>San\u00e7\u00f5es e penalidades<\/h2>\n<p>O pet shop que n\u00e3o se adequar as novas <strong>diretrizes<\/strong> do <strong>Conselho Federal de Medicina Veterin\u00e1ria<\/strong> pode ser autuado e receber uma multa que varia de R$ 6 mil a R$ 24 mil. Desde a aprova\u00e7\u00e3o da Resolu\u00e7\u00e3o, o Conselho vem tentando manter <strong>fiscaliza\u00e7\u00f5es peri\u00f3dicas,<\/strong> buscando que mais estabelecimentos atendam \u00e0s regras impostas pela <strong>nova norma<\/strong>.<\/p>\n<p><strong>Voc\u00ea j\u00e1 conhecia a nova norma para a adequa\u00e7\u00e3o e venda de medicamentos em pet shops? Tem d\u00favidas sobre ela? Seu estabelecimento j\u00e1 est\u00e1 adequado \u00e0s regras? Deixe seus coment\u00e1rios abaixo!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nova norma: os pet shops s\u00f3 poder\u00e3o vender produtos para os animais de estima\u00e7\u00e3o como brinquedos, shampoos, roupinhas, acess\u00f3rios e ra\u00e7\u00f5es.<\/p>\n","protected":false},"author":3,"featured_media":15650,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[],"footnotes":""},"categorias-negocios":[1689],"class_list":["post-14458","negocios","type-negocios","status-publish","has-post-thumbnail","hentry","categorias-negocios-pet-shop"],"_links":{"self":[{"href":"https:\/\/labovet.com.br\/es\/wp-json\/wp\/v2\/negocios\/14458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/labovet.com.br\/es\/wp-json\/wp\/v2\/negocios"}],"about":[{"href":"https:\/\/labovet.com.br\/es\/wp-json\/wp\/v2\/types\/negocios"}],"author":[{"embeddable":true,"href":"https:\/\/labovet.com.br\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/labovet.com.br\/es\/wp-json\/wp\/v2\/comments?post=14458"}],"version-history":[{"count":0,"href":"https:\/\/labovet.com.br\/es\/wp-json\/wp\/v2\/negocios\/14458\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/labovet.com.br\/es\/wp-json\/wp\/v2\/media\/15650"}],"wp:attachment":[{"href":"https:\/\/labovet.com.br\/es\/wp-json\/wp\/v2\/media?parent=14458"}],"wp:term":[{"taxonomy":"categorias-negocios","embeddable":true,"href":"https:\/\/labovet.com.br\/es\/wp-json\/wp\/v2\/categorias-negocios?post=14458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}